{"id":87340,"date":"2023-12-29T12:26:57","date_gmt":"2023-12-29T11:26:57","guid":{"rendered":"https:\/\/lowpressurefitness.com\/producto\/lpf-recursos-adicionales-modulo-2\/"},"modified":"2026-05-12T06:17:28","modified_gmt":"2026-05-12T04:17:28","slug":"lpf-recursos-adicionales-modulo-2","status":"publish","type":"product","link":"https:\/\/lowpressurefitness.com\/en\/producto\/lpf-recursos-adicionales-modulo-2\/","title":{"rendered":"LPF Recursos Adicionales M\u00f3dulo 2"},"content":{"rendered":"<p>\u2605 C\u00d3MO ACCEDO  A LOS CONTENIDOS:<br \/>\nDespu\u00e9s de que validemos tu inscripci\u00f3n, tendr\u00e1s acceso al material en el Aula Virtual Aulands. Si no tienes un perfil previo recibir\u00e1s por correo electr\u00f3nico una clave de acceso y basta que accedas a tu \u00e1rea personal para visualizar los contenidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LPF RECURSOS ADICIONALES DEL CURSO LPF M\u00d3DULO 2<br \/>\nMaterial te\u00f3rico en video adicional a los contenidos y material did\u00e1ctico del M\u00f3dulo 2 LPF. <\/p>\n<p>\u2605  Contenido:<br \/>\n      &#8211; 4 videos  con contenido te\u00f3rico<br \/>\n      &#8211; Master Class del m\u00f3dulo 2<br \/>\n\u2022 Acceso ilimitado<br \/>\n\u2022 Docente: Piti Pinsach Ametller<br \/>\n\u2022 Dirigido a:<br \/>\n&#8211; alumnos matriculados en el curso de m\u00f3dulo 2 LPF.<br \/>\n&#8211;  trainers LPF de nivel  2 (o superior).<\/p>\n","protected":false},"featured_media":2037,"template":"","meta":[],"_links":{"self":[{"href":"https:\/\/lowpressurefitness.com\/en\/wp-json\/wp\/v2\/product\/87340\/"}],"collection":[{"href":"https:\/\/lowpressurefitness.com\/en\/wp-json\/wp\/v2\/product\/"}],"about":[{"href":"https:\/\/lowpressurefitness.com\/en\/wp-json\/wp\/v2\/types\/product\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lowpressurefitness.com\/en\/wp-json\/wp\/v2\/media\/2037\/"}],"wp:attachment":[{"href":"https:\/\/lowpressurefitness.com\/en\/wp-json\/wp\/v2\/media\/?parent=87340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}